{"id":1705,"date":"2016-03-07T09:46:44","date_gmt":"2016-03-07T07:46:44","guid":{"rendered":"http:\/\/www.iosonocirneco.com\/fi\/?page_id=1705"},"modified":"2026-05-12T15:26:25","modified_gmt":"2026-05-12T12:26:25","slug":"cirnecopennut","status":"publish","type":"page","link":"https:\/\/www.iosonocirneco.com\/fi\/pentuja\/cirnecopennut\/","title":{"rendered":"Etnankoiran pennut"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1705\" class=\"elementor elementor-1705\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-170a0075 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"170a0075\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fadfc1b\" data-id=\"1fadfc1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d357ed2 elementor-widget elementor-widget-heading\" data-id=\"d357ed2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Etnankoiran pentuja<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d89c871 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d89c871\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d6284bd\" data-id=\"d6284bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-597f7cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"597f7cf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-354c500\" data-id=\"354c500\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54a4f83 elementor-widget elementor-widget-image\" data-id=\"54a4f83\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2364\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-scaled.jpg\" class=\"attachment-full size-full wp-image-14405\" alt=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-scaled.jpg 2560w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-300x277.jpg 300w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-1024x946.jpg 1024w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-768x709.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-1536x1418.jpg 1536w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-2048x1891.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-046715a\" data-id=\"046715a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf27369 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"cf27369\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">Etnankoiran pentue kes\u00e4ll\u00e4 2026<\/span><\/h2>\n<span style=\"color: #C0C0C0;\">Meill\u00e4 on suunnitelmissa kes\u00e4lle 2026 etnankoirapentue Pumalle (<span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/www.iosonocirneco.com\/fi\/cirneco-dell-etna\/cirnecomme\/hadranensis-lilla\/\">Hadranensis Lilla<\/a><\/span>). Puma syntyi Italiassa ja muutti meille puolen vuoden i\u00e4ss\u00e4. Puma tunnetaan sen vilpitt\u00f6m\u00e4n kiltist\u00e4, avoimesta ja helposta k\u00e4yt\u00f6ksest\u00e4\u00e4n: se rakastaa kaikkia ihmisi\u00e4 ja koiria. Puma on kattavasti terveystarkastettu sek\u00e4 silt\u00e4 l\u00f6ytyy rotuyhdistyksen vaatimat tulokset n\u00e4yttelyst\u00e4 ja k\u00e4ytt\u00f6kokeesta. Puman kanssa harrastamme vapaa-ajallamme agility\u00e4.\u00a0<\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc2cc74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc2cc74\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a3b1789\" data-id=\"a3b1789\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21f28a3 elementor-widget elementor-widget-heading\" data-id=\"21f28a3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kuvia Pumasta<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d25c279 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d25c279\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eedf758\" data-id=\"eedf758\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf1686f elementor-widget elementor-widget-shortcode\" data-id=\"bf1686f\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"> <div  id=\"jtg-14727\" class=\"modula modula-gallery modula-columns\" data-config=\"{&quot;tabletHeight&quot;:800,&quot;mobileHeight&quot;:800,&quot;desktopHeight&quot;:800,&quot;enableTwitter&quot;:false,&quot;enableWhatsapp&quot;:false,&quot;enableFacebook&quot;:false,&quot;enablePinterest&quot;:false,&quot;enableLinkedin&quot;:false,&quot;enableEmail&quot;:false,&quot;randomFactor&quot;:0.5,&quot;type&quot;:&quot;grid&quot;,&quot;columns&quot;:12,&quot;gutter&quot;:1,&quot;mobileGutter&quot;:1,&quot;tabletGutter&quot;:1,&quot;desktopGutter&quot;:1,&quot;enableResponsive&quot;:true,&quot;tabletColumns&quot;:2,&quot;mobileColumns&quot;:1,&quot;lazyLoad&quot;:0,&quot;lightboxOpts&quot;:{&quot;animated&quot;:true,&quot;Thumbs&quot;:{&quot;type&quot;:&quot;modern&quot;,&quot;showOnStart&quot;:false},&quot;Toolbar&quot;:{&quot;display&quot;:{&quot;right&quot;:[&quot;close&quot;]},&quot;enabled&quot;:true},&quot;Carousel&quot;:{&quot;Panzoom&quot;:{&quot;touch&quot;:true},&quot;infinite&quot;:false},&quot;keyboard&quot;:{&quot;Escape&quot;:&quot;close&quot;,&quot;Delete&quot;:&quot;close&quot;,&quot;Backspace&quot;:&quot;close&quot;,&quot;PageUp&quot;:false,&quot;PageDown&quot;:false,&quot;ArrowUp&quot;:false,&quot;ArrowDown&quot;:false,&quot;ArrowRight&quot;:false,&quot;ArrowLeft&quot;:false},&quot;touch&quot;:false,&quot;backdropClick&quot;:false,&quot;l10n&quot;:{&quot;CLOSE&quot;:&quot;Close&quot;,&quot;NEXT&quot;:&quot;Next&quot;,&quot;PREV&quot;:&quot;Previous&quot;,&quot;Error&quot;:&quot;The requested content cannot be loaded. Please try again later.&quot;,&quot;PLAY_START&quot;:&quot;Start slideshow&quot;,&quot;PLAY_STOP&quot;:&quot;Pause slideshow&quot;,&quot;FULL_SCREEN&quot;:&quot;Full screen&quot;,&quot;THUMBS&quot;:&quot;Thumbnails&quot;,&quot;DOWNLOAD&quot;:&quot;Download&quot;,&quot;SHARE&quot;:&quot;Share&quot;,&quot;ZOOM&quot;:&quot;Zoom&quot;,&quot;EMAIL&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;MODAL&quot;:&quot;You can close this modal content with the ESC key&quot;,&quot;ERROR&quot;:&quot;Something Went Wrong, Please Try Again Later&quot;,&quot;IMAGE_ERROR&quot;:&quot;Image Not Found&quot;,&quot;ELEMENT_NOT_FOUND&quot;:&quot;HTML Element Not Found&quot;,&quot;AJAX_NOT_FOUND&quot;:&quot;Error Loading AJAX : Not Found&quot;,&quot;AJAX_FORBIDDEN&quot;:&quot;Error Loading AJAX : Forbidden&quot;,&quot;IFRAME_ERROR&quot;:&quot;Error Loading Page&quot;,&quot;TOGGLE_ZOOM&quot;:&quot;Toggle zoom level&quot;,&quot;TOGGLE_THUMBS&quot;:&quot;Toggle thumbnails&quot;,&quot;TOGGLE_SLIDESHOW&quot;:&quot;Toggle slideshow&quot;,&quot;TOGGLE_FULLSCREEN&quot;:&quot;Toggle full-screen mode&quot;},&quot;Images&quot;:{&quot;Panzoom&quot;:{&quot;maxScale&quot;:2}},&quot;mainClass&quot;:&quot;modula-fancybox-container modula-lightbox-jtg-14727&quot;,&quot;Html&quot;:{&quot;videoAutoplay&quot;:0,&quot;videoTpl&quot;:&quot;&lt;video class=\\&quot;fancybox__html5video\\&quot; controls muted playsinline controlsList controlsList=\\&quot;nodownload\\&quot; poster=\\&quot;{{poster}}\\&quot; src=\\&quot;{{src}}\\&quot; type=\\&quot;{{format}}\\&quot; &gt;  Sorry, your browser doesn&#039;t support embedded videos, &lt;a href=\\&quot;{{src}}\\&quot;&gt; download &lt;\\\/a&gt; and watch with your favorite video player! &lt;\\\/video&gt;&quot;}},&quot;inView&quot;:false,&quot;email_subject&quot;:&quot;Check out this awesome image !!&quot;,&quot;email_message&quot;:&quot;Here is the link to the image : %%image_link%% and this is the link to the gallery : %%gallery_link%%&quot;,&quot;grid_type&quot;:&quot;5&quot;,&quot;rowHeight&quot;:250,&quot;lastRow&quot;:&quot;justify&quot;,&quot;lightbox&quot;:&quot;fancybox&quot;}\">\n\n\t<div class=\"modula-grid-sizer\"> <\/div>\n\t<div  class=\"modula-items grid-gallery\">\n\t\t<div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14733\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14733\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/puma-lenkilla.jpg\" title=\"puma-lenkilla\" crop=\"\" width=\"576\" height=\"1024\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/puma-lenkilla-576x1024.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/puma-lenkilla-576x1024.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/puma-lenkilla-scaled.jpg 1440w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/puma-lenkilla-169x300.jpg 169w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/puma-lenkilla-scaled-576x1024.jpg 576w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/puma-lenkilla-768x1365.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/puma-lenkilla-864x1536.jpg 864w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/puma-lenkilla-1152x2048.jpg 1152w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14408\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14408\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_3552.jpg\" title=\"IMG_3552\" crop=\"\" width=\"605\" height=\"1024\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_3552-605x1024.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_3552-605x1024.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_3552-scaled.jpg 1513w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_3552-177x300.jpg 177w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_3552-scaled-605x1024.jpg 605w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_3552-768x1300.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_3552-908x1536.jpg 908w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_3552-1210x2048.jpg 1210w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14037\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14037\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24b.jpg\" title=\"puma-24b\" crop=\"\" width=\"1024\" height=\"976\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24b-1024x976.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24b-1024x976.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24b-scaled.jpg 2560w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24b-300x286.jpg 300w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24b-scaled-1024x976.jpg 1024w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24b-768x732.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24b-1536x1464.jpg 1536w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24b-2048x1953.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14729\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14729\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumatausta.jpg\" title=\"pumatausta\" crop=\"\" width=\"819\" height=\"1024\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumatausta-819x1024.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumatausta-819x1024.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumatausta-scaled.jpg 2048w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumatausta-240x300.jpg 240w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumatausta-scaled-819x1024.jpg 819w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumatausta-768x960.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumatausta-1229x1536.jpg 1229w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumatausta-1638x2048.jpg 1638w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14015\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14015\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24.jpg\" title=\"puma-24\" crop=\"\" width=\"1024\" height=\"1014\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24-1024x1014.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24-1024x1014.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24-scaled.jpg 2560w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24-300x297.jpg 300w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24-scaled-1024x1014.jpg 1024w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24-150x150.jpg 150w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24-768x760.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24-1536x1520.jpg 1536w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-24-2048x2027.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14405\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14405\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1.jpg\" title=\"pumahead1\" crop=\"\" width=\"1024\" height=\"946\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-1024x946.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-1024x946.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-scaled.jpg 2560w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-300x277.jpg 300w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-scaled-1024x946.jpg 1024w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-768x709.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-1536x1418.jpg 1536w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/pumahead1-2048x1891.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14411\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14411\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5410.jpg\" title=\"IMG_5410\" crop=\"\" width=\"576\" height=\"1024\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5410-576x1024.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5410-576x1024.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5410-scaled.jpg 1440w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5410-169x300.jpg 169w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5410-scaled-576x1024.jpg 576w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5410-768x1365.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5410-864x1536.jpg 864w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5410-1152x2048.jpg 1152w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14412\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14412\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_9156.jpg\" title=\"IMG_9156\" crop=\"\" width=\"1024\" height=\"768\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_9156-1024x768.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_9156-1024x768.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_9156-scaled.jpg 2560w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_9156-300x225.jpg 300w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_9156-scaled-1024x768.jpg 1024w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_9156-768x576.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_9156-1536x1152.jpg 1536w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_9156-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14409\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14409\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5409.jpg\" title=\"IMG_5409\" crop=\"\" width=\"768\" height=\"1024\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5409-768x1024.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5409-768x1024.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5409-scaled.jpg 1920w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5409-225x300.jpg 225w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5409-scaled-768x1024.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5409-1152x1536.jpg 1152w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/IMG_5409-1536x2048.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14038\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14038\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-23.jpg\" title=\"puma-23\" crop=\"\" width=\"801\" height=\"1024\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-23-801x1024.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-23-801x1024.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-23-scaled.jpg 2003w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-23-235x300.jpg 235w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-23-scaled-801x1024.jpg 801w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-23-768x982.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-23-1202x1536.jpg 1202w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-23-1602x2048.jpg 1602w\" sizes=\"auto, (max-width: 801px) 100vw, 801px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14016\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14016\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-3-24.jpg\" title=\"puma-heinakuu-3-24\" crop=\"\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-3-24-1024x1024.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-3-24-1024x1024.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-3-24-scaled.jpg 2560w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-3-24-300x300.jpg 300w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-3-24-scaled-1024x1024.jpg 1024w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-3-24-150x150.jpg 150w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-3-24-1536x1536.jpg 1536w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-3-24-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"13543\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-13543\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2023\/02\/puma9kk.jpg\" title=\"puma9kk\" crop=\"\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2023\/02\/puma9kk-1024x1024.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2023\/02\/puma9kk-1024x1024.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2023\/02\/puma9kk-300x300.jpg 300w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2023\/02\/puma9kk-1024x1024.jpg 1024w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2023\/02\/puma9kk-150x150.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t<\/div>\n\n<\/div><div class=\"modula-item\" >\n\t<div class=\"modula-item-content\">\n\t\t\n\t\t\t\t\t<a data-image-id=\"14017\" role=\"button\" data-elementor-open-lightbox=\"no\" tabindex=\"0\" rel=\"jtg-14727\" data-caption=\"\" aria-label=\"Open image in lightbox\" class=\"tile-inner modula-item-link\"><\/a>\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" class=\"pic wp-image-14017\"  data-valign=\"middle\" data-halign=\"center\" alt=\"\" data-full=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-4-24.jpg\" title=\"puma-heinakuu-4-24\" crop=\"\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-4-24-1024x1024.jpg\" data-src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-4-24-1024x1024.jpg\" data-caption=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-4-24-scaled.jpg 2560w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-4-24-300x300.jpg 300w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-4-24-scaled-1024x1024.jpg 1024w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-4-24-150x150.jpg 150w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-4-24-1536x1536.jpg 1536w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2024\/08\/puma-heinakuu-4-24-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\n\t<\/div>\n\n<\/div>\t\t\n\t<\/div>\n\n\t\n\t\n\t<script type=\"application\/ld+json\">\n\t{\n\t\t\"@context\": \"https:\/\/schema.org\",\n\t\t\"@type\"   : \"ImageGallery\",\n\t\t\"id\"      : \"https:\/\/www.iosonocirneco.com\/fi\/pentuja\/cirnecopennut\/#modula-gallery-14727\",\n\t\t\"url\"     : \"https:\/\/www.iosonocirneco.com\/fi\/pentuja\/cirnecopennut\/\"\n\t}\n\n\t<\/script>\n\n\t\n<\/div>\n <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-deb6f93 elementor-widget elementor-widget-spacer\" data-id=\"deb6f93\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c0d4b6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0d4b6a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec16b03\" data-id=\"ec16b03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-db3d165 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db3d165\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-07447f8\" data-id=\"07447f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1496111 elementor-widget elementor-widget-image\" data-id=\"1496111\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1674\" height=\"1674\" src=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/katlapaa1.jpg\" class=\"attachment-full size-full wp-image-14203\" alt=\"\" srcset=\"https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/katlapaa1.jpg 1674w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/katlapaa1-300x300.jpg 300w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/katlapaa1-1024x1024.jpg 1024w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/katlapaa1-150x150.jpg 150w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/katlapaa1-768x768.jpg 768w, https:\/\/www.iosonocirneco.com\/fi\/wp-content\/uploads\/2026\/05\/katlapaa1-1536x1536.jpg 1536w\" sizes=\"auto, (max-width: 1674px) 100vw, 1674px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-541edad\" data-id=\"541edad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c890cd4 elementor-widget elementor-widget-text-editor\" data-id=\"c890cd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">Etnankoiran pentue kev\u00e4\u00e4ll\u00e4 2027<\/span><\/h2>\n<p>Toinen etnankoirapentueemme on suunnitteilla 2027 Katlalle. Katla on oma kasvattimme jo 6. polvessa ja se on hyvin monipuolinen harrastuskoira. Se kilpailee agilityss\u00e4 korkeimmassa luokassa (hyppyrata), on k\u00e4ytt\u00f6valio maastojuoksusta sek\u00e4 n\u00e4yttelyiss\u00e4 Katla on niitt\u00e4nyt menestyst\u00e4 mm. ollen vuoden voitokkain etnankoira vuonna 2024 Katla on virallisemmin: FI MVA, EE MVA, FI KVA-VIC, EE KVA-VIC, FI &amp; EE JMVA, HeW-24, HeW-25, CVM-25, Suomen Voitokkain Cirneco 2024 <span style=\"color: #ffffff;\">Iosono Elysiana<\/span>.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e17c666 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e17c666\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d582dde\" data-id=\"d582dde\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d381d03 elementor-widget elementor-widget-heading\" data-id=\"d381d03\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pentu meilt\u00e4<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8691c4 elementor-widget elementor-widget-text-editor\" data-id=\"a8691c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Jos olet kiinnostunut etnankoirapennusta, ota yhteytt\u00e4! Kerromme my\u00f6s mielell\u00e4mme yleisestikin etnankoirasta rotuna, jos rotu kiinnostaa sinua.<\/p>\n<p>Kun otat yhteytt\u00e4, kerrothan samalla itsest\u00e4si, millaiseen kotiin pentu tulisi, miss\u00e4 p\u00e4in asut sek\u00e4 mahdollisesta koirahistoriastasi. Kerro my\u00f6s, miksi rotu kiinnostaa sinua.<\/p>\n<p>Etsimme meid\u00e4n kasvattamille pennuille ensisijaisesti yhteisty\u00f6kykyisi\u00e4, rakastavia rotuun paneutuneita loppuel\u00e4m\u00e4n koteja. Haluamme aina tavata pennustamme kiinnostuneen ihmisen tai parhaassa tapauksessa koko perheen kasvotusten ennen mahdollista lupausta pennun saamisesta. Toivomme my\u00f6s, ett\u00e4 kasvatinomistajamme sitoutuisivat tutkimaan virallisesti koiransa terveyden v\u00e4hint\u00e4\u00e4n silmien ja polvien osalta. My\u00f6s ns. kotikoirille tehdyt viralliset terveystutkimukset edesauttavat rodun jalostusta kasvattajien tehdess\u00e4 jalostusp\u00e4\u00e4t\u00f6ksi\u00e4.<\/p>\n<p>Etnankoirapentumme luovutetaan 7-8 -viikkoisena madotettuina, el\u00e4inl\u00e4\u00e4k\u00e4rin tarkastamina, tunnistusmerkittyin\u00e4 sek\u00e4 rekister\u00f6ityin\u00e4 Suomen Kennelliittoon ja Ruokavirastoon. Ennen luovutusik\u00e4\u00e4 pyrimme sosiaalistamaan pentuja mahdollisimman paljon ja tutustuttamaan pentuja erilaisiin ymp\u00e4rist\u00f6ihin. Ruokimme pentumme niin raakaruoalla kuin nappulalla. Tarjoamme kasvatinomistajillemme aina 24\/7-tuen ja haluamme my\u00f6s kuulla kasvattiemme kuulumisia l\u00e4pi koirien el\u00e4m\u00e4n.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69ad595 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69ad595\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6caedbd\" data-id=\"6caedbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-234d1b3 elementor-widget elementor-widget-spacer\" data-id=\"234d1b3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-acb25aa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"acb25aa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f0c811\" data-id=\"0f0c811\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caf4b66 elementor-widget elementor-widget-text-editor\" data-id=\"caf4b66\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>OTA<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d80d696 elementor-widget elementor-widget-heading\" data-id=\"d80d696\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">YHTEYTT\u00c4<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95c3534 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95c3534\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cca9526\" data-id=\"cca9526\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd1c024 elementor-widget elementor-widget-text-editor\" data-id=\"dd1c024\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Erja Luomanm\u00e4ki &amp; Inka Forss<br \/>Helsinki \u2013 Espoo<br \/><a href=\"mailto:iosonocirneco@gmail.com\">iosonocirneco@gmail.com<\/a><br \/>040 568 0179 (Erja)<br \/>040 165 7010 (Inka)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Etnankoiran pentuja Etnankoiran pentue kes\u00e4ll\u00e4 2026 Meill\u00e4 on suunnitelmissa kes\u00e4lle 2026 etnankoirapentue Pumalle (Hadranensis Lilla). Puma syntyi Italiassa ja muutti meille puolen vuoden i\u00e4ss\u00e4. Puma tunnetaan sen vilpitt\u00f6m\u00e4n kiltist\u00e4, avoimesta ja helposta k\u00e4yt\u00f6ksest\u00e4\u00e4n: se rakastaa kaikkia ihmisi\u00e4 ja koiria. Puma on kattavasti terveystarkastettu sek\u00e4 silt\u00e4 l\u00f6ytyy rotuyhdistyksen vaatimat tulokset n\u00e4yttelyst\u00e4 ja k\u00e4ytt\u00f6kokeesta. Puman kanssa harrastamme&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":13,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-1705","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.iosonocirneco.com\/fi\/wp-json\/wp\/v2\/pages\/1705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iosonocirneco.com\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.iosonocirneco.com\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.iosonocirneco.com\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iosonocirneco.com\/fi\/wp-json\/wp\/v2\/comments?post=1705"}],"version-history":[{"count":206,"href":"https:\/\/www.iosonocirneco.com\/fi\/wp-json\/wp\/v2\/pages\/1705\/revisions"}],"predecessor-version":[{"id":15615,"href":"https:\/\/www.iosonocirneco.com\/fi\/wp-json\/wp\/v2\/pages\/1705\/revisions\/15615"}],"up":[{"embeddable":true,"href":"https:\/\/www.iosonocirneco.com\/fi\/wp-json\/wp\/v2\/pages\/13"}],"wp:attachment":[{"href":"https:\/\/www.iosonocirneco.com\/fi\/wp-json\/wp\/v2\/media?parent=1705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}